{"id":13588,"date":"2017-01-09T09:12:00","date_gmt":"2017-01-09T09:12:00","guid":{"rendered":""},"modified":"2017-01-09T09:12:00","modified_gmt":"2017-01-09T09:12:00","slug":"artigo13588","status":"publish","type":"post","link":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/artigo13588\/","title":{"rendered":"ANTE O DIV\u00d3RCIO  &#8211; Casamento"},"content":{"rendered":"<p>Tema : Lar e Div\u00f3rcio Toda perturba\u00e7\u00e3o no lar, frustrando lhe a viagem no tempo, tem causa espec\u00edfica. Qual acontece ao comboio, quando estaca indebitamente ou descarrila, \u00e9 imperioso angariar a prote\u00e7\u00e3o devida para que o carro dom\u00e9stico prossiga adiante.<br \/>No transporte caseiro, aparentemente ancorado na esta\u00e7\u00e3o do cotidiano ( e dizemos aparentemente, porque a m\u00e1quina familiar est\u00e1 em movimento e transforma\u00e7\u00e3o incessantes ), quase todos os acidentes se verificam pela evid\u00eancia de falhas diminutas que, em se repetindo indefinidamente, estabelecem, por fim, o desastre espetacular.<br \/>Essas falhas, no entanto, nascem do comportamento dos mais interessados na sustenta\u00e7\u00e3o do ve\u00edculo ou, propriamente, do marido e da mulher, chamados pela a\u00e7\u00e3o da vida a regenerar o passado ou a construir o futuro pelas possibilidades da reencarna\u00e7\u00e3o no presente, falhas essas que se manifestam de pequeno desequil\u00edbrio, at\u00e9 que se desencadeie o desequil\u00edbrio maior.<br \/>Nesse sentido, vemos c\u00f4njuges que transfiguram conforto em pletora de luxo e dinheiro, desfazendo o matrim\u00f4nio em facilidades loucas, como se afoga uma planta por excesso de adubo, e observamos aqueles outros que o sufocam por abuso de sovinice, notamos os que arrasam a uni\u00e3o conjugal em festas sociais permanentes e assinalamos os que a destroem por demasia de solid\u00e3o, encontramos os campe\u00f5es da teimosia que acabam com a paz em fam\u00edlia, manejando atitudes do contra sistem\u00e1tico, diante de tudo e de todos, e identificamos os que a exterminam pelo sil\u00eancio culposo, \u00e0 frente do mal, surpreendemos os fan\u00e1ticos da limpeza, principalmente muitas de nossas irm\u00e3s, as mulheres, quando se fazem m\u00e1rtires de vassoura e enceradeira, dispostas a arruinar o acordo geral em raz\u00e3o de leve cisco nos m\u00f3veis, e somos defrontados pelos que primam no v\u00edcio de enlamear a casa, desprezando a higiene.<br \/>Equil\u00edbrio e respeito m\u00fatuo s\u00e3o as bases do trabalho de quantos se prop\u00f5em garantir a felicidade conjugal, de vez que, repitamos, o lar \u00e9 semelhante ao comboio em que filhos, parentes, tutores e afei\u00e7oados s\u00e3o passageiros.<br \/>Algu\u00e9m perguntar\u00e1 como situaremos o div\u00f3rcio nestas compara\u00e7\u00f5es. Divorciar, a nosso ver, \u00e9 deixar a locomotiva e seus anexos. Quem responde pela iniciativa da separa\u00e7\u00e3o decerto que larga todo esse instrumental de servi\u00e7o \u00e0 pr\u00f3pria sorte e cada consci\u00eancia \u00e9 respons\u00e1vel por si. N\u00e3o ignoramos que o trem caseiro corre nos trilhos da exist\u00eancia terrestre, com autoriza\u00e7\u00e3o e administra\u00e7\u00e3o das Leis Org\u00e2nicas da Provid\u00eancia Divina e, sendo assim, o div\u00f3rcio, expressando desist\u00eancia ou abandono de compromisso, \u00e9 decis\u00e3o lastim\u00e1vel, conquanto \u00e0s vezes necess\u00e1ria, com ra\u00edzes na responsabilidade do esposo ou da esposa que, a rigor, no caso, exercem as fun\u00e7\u00f5es de chefe e maquinista.<br \/>Esp\u00edrito : Emmanuel.<br \/>Psicografia : Francisco C\u00e2ndido Xavier Livro : Encontro Marcado &#8211; Cap. 51<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_13588\" class=\"pvc_stats all  \" data-element-id=\"13588\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/www.centronocaminhodaluz.com.br\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tema : Lar e Div\u00f3rcio Toda perturba\u00e7\u00e3o no lar, frustrando lhe a viagem no tempo, tem causa espec\u00edfica. Qual acontece ao comboio, quando estaca indebitamente ou descarrila, \u00e9 imperioso angariar a prote\u00e7\u00e3o devida para que o carro dom\u00e9stico prossiga adiante.No transporte caseiro, aparentemente ancorado na esta\u00e7\u00e3o do cotidiano ( e dizemos aparentemente, porque a m\u00e1quina&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/artigo13588\/\">Leia mais<\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_13588\" class=\"pvc_stats all  \" data-element-id=\"13588\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/www.centronocaminhodaluz.com.br\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"Closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-13588","post","type-post","status-publish","format-standard","hentry","category-mensagens-diversas"],"a3_pvc":{"activated":true,"total_views":1299,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13588"}],"version-history":[{"count":0,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13588\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}