{"id":13673,"date":"2017-02-20T08:12:00","date_gmt":"2017-02-20T08:12:00","guid":{"rendered":""},"modified":"2017-02-20T08:12:00","modified_gmt":"2017-02-20T08:12:00","slug":"artigo13673","status":"publish","type":"post","link":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/artigo13673\/","title":{"rendered":"ONDE EST\u00c1 VOC\u00ca? &#8211; Reda\u00e7\u00e3o do Momento Esp\u00edrita"},"content":{"rendered":"<p>Onde est\u00e1 voc\u00ea com seus pensamentos nesse momento?<br \/>\n<br \/>    Ser\u00e1 que est\u00e1 presente na conversa com os amigos, ou est\u00e1 longe, viajando por lugares distantes?<br \/>\n<br \/>    Onde est\u00e1 sua felicidade agora?<br \/>\n<br \/>    Ser\u00e1 que est\u00e1 junto de voc\u00ea, ou est\u00e1 longe, em objetos distantes, em pessoas que se foram em bens materiais que voc\u00ea ainda n\u00e3o tem?<br \/>\n<br \/>    Onde est\u00e1 seu sorriso agora?<br \/>\n<br \/>    Est\u00e1 em seu rosto, estampando a sua alegria e confian\u00e7a na vida?<br \/>\n<br \/>    Ou ser\u00e1 que foi levado por algu\u00e9m que n\u00e3o est\u00e1 mais aqui?<br \/>\n<br \/>    Ser\u00e1 que seu sorriso ainda depende dos outros?<br \/>\n<br \/>    Onde est\u00e1 a sua vontade de viver, agora?<br \/>\n<br \/>    Est\u00e1 a\u00ed mesmo dentro de voc\u00ea chamando-o, a cada minuto, para as oportunidades, para viver os dias, ou est\u00e1 nas m\u00e3os de outras pessoas, e voc\u00ea est\u00e1 perdido sem saber para onde ir?<br \/>\n<br \/>    Quem \u00e9 o dono da sua vida, da sua vontade e da sua motiva\u00e7\u00e3o?<br \/>\n<br \/>    O que voc\u00ea precisa para ser feliz agora?<br \/>\n<br \/>    Um emprego? Ser\u00e1 que voc\u00ea n\u00e3o consegue procurar um pouco mais? Quem sabe mudar os rumos? Ou procurar em lugares onde voc\u00ea nunca havia procurado antes?<br \/>\n<br \/>    N\u00e3o coloque para si mesmo obst\u00e1culos demais!<br \/>\n<br \/>    Ser\u00e1 que a felicidade est\u00e1 apenas na conquista de um emprego?<br \/>\n<br \/>    Talvez voc\u00ea precise de um amor.<br \/>\n<br \/>    Ent\u00e3o cultive novas amizades! Lembre-se de que a amizade \u00e9 a fonte do amor verdadeiro!<br \/>\n<br \/>    Procure se aproximar mais das pessoas, quem sabe!<br \/>\n<br \/>    Antes de querer ser amado, ame!<br \/>\n<br \/>    Onde est\u00e1 seu Deus agora?<br \/>\n<br \/>    Ser\u00e1 que voc\u00ea j\u00e1 o descobriu dentro de voc\u00ea?<br \/>\n<br \/>    Ser\u00e1 que voc\u00ea j\u00e1 o descobriu nas leis maravilhosas que regem o universo? Na prote\u00e7\u00e3o que recebemos, nas chances, nos encontros, nas b\u00ean\u00e7\u00e3os da vida?<br \/>\n<br \/>    Ser\u00e1 que voc\u00ea j\u00e1 o descobriu nas estrelas, nos mares, nos ventos, no perfume das flores?<br \/>\n<br \/>    Onde est\u00e1 voc\u00ea agora?<br \/>\n<br \/>    No curso mais seguro da vida, tendo sua embarca\u00e7\u00e3o sob controle? Ou est\u00e1 \u00e0 deriva? Distra\u00eddo pelas ilus\u00f5es que encrespam o oceano todos os dias?<br \/>\n<br \/>    Onde est\u00e1 voc\u00ea agora?<br \/>\n<br \/>    Buscando um sentido maior para tudo, buscando o crescimento espiritual, ou est\u00e1 preocupado com coisas t\u00e3o pequenas, incomodado com problemas t\u00e3o simples?<br \/>\n<br \/>    \u00c9 tempo de saber onde realmente estamos.<br \/>\n<br \/>    \u00c9 tempo de repensar muitas coisas, de dar um novo sentido a tudo, de redescobrir as coisas mais simples e poss\u00edveis, e recriar a vida,colocando-a em seu curso seguro.<br \/>\n<br \/>    Como nos ensinou o Mestre de Nazar\u00e9, onde estiver seu cora\u00e7\u00e3o, a\u00ed estar\u00e1 tamb\u00e9m o seu tesouro.<br \/>\n<br \/>    Pense nisso!<br \/>\n<br \/>    Por vezes nossos olhares se perdem no espa\u00e7o \u00e0 procura de algo que se encontra bem perto de n\u00f3s.<br \/>\n<br \/>    Outras vezes permitimos que nosso sorriso siga atrelado ao passo de algu\u00e9m que se afasta de n\u00f3s&#8230;<br \/>\n<br \/>    Nossa alegria, tantas vezes, perde a for\u00e7a por causa de algo insignificante.<br \/>\n<br \/>    \u00c0s vezes permitirmos que a nossa vontade de viver se enfraque\u00e7a, vencida pelas ilus\u00f5es e fantasias&#8230;<br \/>\n<br \/>    No entanto, para que n\u00e3o deixemos de viver o momento, intensamente, \u00e9 preciso prestar aten\u00e7\u00e3o nas horas, no agora, no hoje, para que n\u00e3o deixemos escapar as mais excelentes oportunidades de construir nossa felicidade duradoura.<br \/>\n<br \/>    Pensemos nisso!<\/p>\n<p>(Equipe de Reda\u00e7\u00e3o do Momento Esp\u00edrita, a partir de texto de autoria desconhecida). &#8211; www.momento.org.br)<br \/>\n<br \/>Fonte: CVDEE &#8211; Centro Virtual de Divulga\u00e7\u00e3o e Estudo do Espiritismo<br \/>\n<br \/>www.cvdee.org.br<br \/>\n<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_13673\" class=\"pvc_stats all  \" data-element-id=\"13673\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/www.centronocaminhodaluz.com.br\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Onde est\u00e1 voc\u00ea com seus pensamentos nesse momento? Ser\u00e1 que est\u00e1 presente na conversa com os amigos, ou est\u00e1 longe, viajando por lugares distantes? Onde est\u00e1 sua felicidade agora? Ser\u00e1 que est\u00e1 junto de voc\u00ea, ou est\u00e1 longe, em objetos distantes, em pessoas que se foram em bens materiais que voc\u00ea ainda n\u00e3o tem? Onde&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/artigo13673\/\">Leia mais<\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_13673\" class=\"pvc_stats all  \" data-element-id=\"13673\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/www.centronocaminhodaluz.com.br\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"Closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-13673","post","type-post","status-publish","format-standard","hentry","category-mensagens-diversas"],"a3_pvc":{"activated":true,"total_views":3010,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13673"}],"version-history":[{"count":0,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13673\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}