{"id":17690,"date":"2021-01-30T09:12:00","date_gmt":"2021-01-30T09:12:00","guid":{"rendered":"http:\/\/www.centronocaminhodaluz.com.br\/index.php\/artigo17690\/"},"modified":"2021-01-30T09:30:52","modified_gmt":"2021-01-30T12:30:52","slug":"artigo17690","status":"publish","type":"post","link":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/artigo17690\/","title":{"rendered":"14 &#8211; BOMBEIROS DE DEUS &#8211; Mensagens de Emmanuel"},"content":{"rendered":"<p>14 &#8211; BOMBEIROS DE DEUS<\/p>\n<p>Temos diversas formas de auxiliar:<br \/>suprimir a pen\u00faria, <br \/>estender a benefic\u00eancia, <br \/>criar a generosidade<br \/>consolar o sofrimento.<br \/>Existe por\u00e9m, uma delas ao alcance de todos e que pode ser largamente exercida em qualquer lugar : o donativo da<br \/>calma nos momentos atribulados da vida.<br \/>Recorda os bens espirituais que consegues distribuir e n\u00e3o marginalizes semelhante recurso.<br \/>Diante de reclama\u00e7\u00f5es e cr\u00edticas, usa a toler\u00e2ncia que estabele\u00e7a a harmonia poss\u00edvel entre acusados e acusadores, <br \/>recebendo inj\u00farias e ofensas, silencia e esquece os desequil\u00edbrios de que porventura te fizeste v\u00edtima, sustando<br \/>calamidades da delinqu\u00eancia, perante a agressividade exagerada de algu\u00e9m, guarda a serenidade que balsamize cora\u00e7\u00f5es<br \/>e pacifique ambientes, encontrando ve\u00edculos de disc\u00f3rdia, emprega o entendimento que afaste choques e conflitos<br \/>capazes de suscitar azedume e perturba\u00e7\u00e3o.<br \/>Em qualquer lance dif\u00edcil da exist\u00eancia, disp\u00f5es da possibilidade de atuar beneficamente com os recursos da bondade e<br \/>da compreens\u00e3o que entretecem a garantia da paz.<br \/>Lembra a fa\u00edsca lan\u00e7ada impensadamente quando se transforma em fogo descontrolado e devorador.<br \/>Qualquer criatura, quando se mostre agindo sem no\u00e7\u00e3o de responsabilidade pode gerar inc\u00eandios lament\u00e1veis, <br \/>destruindo os mais altos valores da vida.<br \/>Por isso mesmo, onde estivermos, sejamos n\u00f3s os bombeiros de Deus.<\/p>\n<p>Esp\u00edrito: EMMANUEL<br \/>M\u00e9dium: Francisco C\u00e2ndido Xavier<br \/>Livro: &#8220;Caminhos de Volta&#8221; &#8211; EDI\u00c7\u00c3O GEEM<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_17690\" class=\"pvc_stats all  \" data-element-id=\"17690\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/www.centronocaminhodaluz.com.br\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>14 &#8211; BOMBEIROS DE DEUS Temos diversas formas de auxiliar:suprimir a pen\u00faria, estender a benefic\u00eancia, criar a generosidadeconsolar o sofrimento.Existe por\u00e9m, uma delas ao alcance de todos e que pode ser largamente exercida em qualquer lugar : o donativo dacalma nos momentos atribulados da vida.Recorda os bens espirituais que consegues distribuir e n\u00e3o marginalizes semelhante&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/artigo17690\/\">Leia mais<\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_17690\" class=\"pvc_stats all  \" data-element-id=\"17690\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/www.centronocaminhodaluz.com.br\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-17690","post","type-post","status-publish","format-standard","hentry","category-mensagens-diversas"],"a3_pvc":{"activated":true,"total_views":570,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=17690"}],"version-history":[{"count":0,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17690\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=17690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=17690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=17690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}