{"id":17759,"date":"2021-02-20T09:12:00","date_gmt":"2021-02-20T09:12:00","guid":{"rendered":"http:\/\/www.centronocaminhodaluz.com.br\/index.php\/artigo17759\/"},"modified":"2021-02-20T09:27:28","modified_gmt":"2021-02-20T12:27:28","slug":"artigo17759","status":"publish","type":"post","link":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/artigo17759\/","title":{"rendered":"Quem desliga? &#8211; Reda\u00e7\u00e3o do Momento Esp\u00edrita"},"content":{"rendered":"<p>\n<br \/>N\u00e3o h\u00e1 ningu\u00e9m que visite o espet\u00e1culo das Cataratas do Igua\u00e7u e fique indiferente.<\/p>\n<p>\u00c9 verdadeiramente grandioso observar as quedas d\u00b4\u00e1gua, que variam de quarenta a oitenta metros de altura.<br \/> Dependendo da vaz\u00e3o do rio, o n\u00famero de saltos tamb\u00e9m varia, chegando a mais de duzentos.<\/p>\n<p>Numa li\u00e7\u00e3o de solidariedade, cinco, do total de dezenove saltos principais, est\u00e3o do lado brasileiro.<br \/> Os demais, do lado argentino.<\/p>\n<p>Como esses est\u00e3o voltados para o Brasil, a melhor vista para quem observa o cen\u00e1rio \u00e9 do lado brasileiro.<\/p>\n<p>A forma\u00e7\u00e3o do acidente geogr\u00e1fico das Cataratas se iniciou h\u00e1 aproximadamente duzentos mil anos, embora a forma\u00e7\u00e3o geol\u00f3gica date de cento e cinquenta milh\u00f5es de anos.<\/p>\n<p>Entre os meses de outubro a mar\u00e7o, normalmente, \u00e9 maior o volume de \u00e1gua, chegando a mil e quinhentos metros c\u00fabicos por segundo.<\/p>\n<p>Por isso mesmo, a sinfonia das quedas d\u00b4\u00e1gua pode ser ouvida de longe, num ronco quase ensurdecedor, \u00e0 medida que as pessoas se aproximam das maiores quedas.<\/p>\n<p>\u00c9 como a apoteose de um grand finale que, no entanto, n\u00e3o acaba.<\/p>\n<p>E foi ali, ante a beleza das \u00e1guas se precipitando sem cansa\u00e7o, numa dan\u00e7a incessante, levantando nuvens brancas nas quedas, que uma menina de seus quatro anos olhou para a tia, que a conduzia pela m\u00e3o, e perguntou:<br \/>\n<br \/>Quando o homem vai desligar isso tudo?<br \/>\n<br \/>De imediato, os que se encontravam pr\u00f3ximos, sorriram da ingenuidade da garota.<\/p>\n<p>Mas, que extraordin\u00e1ria indaga\u00e7\u00e3o!<br \/>\n<br \/>Em contemplando aquela beleza toda, se sucedendo em tantos saltos, a abund\u00e2ncia das \u00e1guas, o arco-\u00edris enorme indo de um lado a outro das fronteiras, ela logo imaginou que algu\u00e9m devia estar por tr\u00e1s daquilo tudo.<\/p>\n<p>Em casa, ela sabe que \u00e9 algu\u00e9m que aciona o interruptor para ligar e desligar a luz el\u00e9trica.<br \/> As torneiras s\u00e3o abertas e fechadas.<\/p>\n<p>Quem, pois, se encarregava de fechar as torneiras para que a \u00e1gua parasse de saltar, se precipitar e correr rio abaixo?<br \/>\n<br \/>Com certeza, essa mesma menina, deve ter interrogado quem acende as estrelas de noite e coloca o sol a brilhar durante o dia.<\/p>\n<p>Quem aciona a chuva, quem liga os potentes ventiladores para soprarem os ventos, quem estende o manto da noite.<\/p>\n<p>Todos os seres inteligentes, ante o assombro das belezas naturais, indagam: Quem fez tudo isso?<br \/>\n<br \/>E as maiores mentes da Humanidade fizeram as mesmas perguntas e somente quem \u00e9 pequeno n\u00e3o se d\u00e1 conta que, por tr\u00e1s de toda a grandiosidade do planeta, h\u00e1 uma mente genial, inigual\u00e1vel.<\/p>\n<p>Algu\u00e9m que supera todas as intelig\u00eancias, toda a criatividade e toda excel\u00eancia das virtudes.<\/p>\n<p>Podemos chamar For\u00e7a da Natureza, Incognosc\u00edvel, Ideia M\u00e3e, Ideia Diretriz, Arquiteto do Universo.<br \/> Como queiramos e como entendamos.<\/p>\n<p>No entanto, quem quer que tenha ouvidos de ouvir, poder\u00e1 escutar o sussurro do vento, o murm\u00fario da chuva, o ribombar dos trov\u00f5es a recitar o mesmo mantra: \u00c9 Deus! \u00c9 Deus!<br \/>\n<br \/>E, foi por isso, que a tia, olhando a sobrinha encantada, lhe respondeu: Deus n\u00e3o desliga, querida!<br \/>\n<br \/>*   *   *<br \/>\n<br \/>Pensemos nisso: Deus n\u00e3o desliga nem as \u00e1guas, nem os ventos, nem as estrelas.<br \/> Ele est\u00e1 sempre atento e Seu amor se derrama por sobre todo o Universo, continuamente.<\/p>\n<p>Ou\u00e7amos a natureza: \u00c9 Deus! \u00c9 Deus!<br \/>\n<br \/>Reda\u00e7\u00e3o do Momento Esp\u00edrita, com base em<br \/>\n<br \/>fato narrado por Ana Paula Sala Moreno,<br \/>\n<br \/>de Foz do Igua\u00e7u.<\/p>\n<p>Em 26.<br \/>1.<br \/>2021.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_17759\" class=\"pvc_stats all  \" data-element-id=\"17759\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/www.centronocaminhodaluz.com.br\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e3o h\u00e1 ningu\u00e9m que visite o espet\u00e1culo das Cataratas do Igua\u00e7u e fique indiferente. \u00c9 verdadeiramente grandioso observar as quedas d\u00b4\u00e1gua, que variam de quarenta a oitenta metros de altura. Dependendo da vaz\u00e3o do rio, o n\u00famero de saltos tamb\u00e9m varia, chegando a mais de duzentos. Numa li\u00e7\u00e3o de solidariedade, cinco, do total de dezenove&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/artigo17759\/\">Leia mais<\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_17759\" class=\"pvc_stats all  \" data-element-id=\"17759\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/www.centronocaminhodaluz.com.br\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-17759","post","type-post","status-publish","format-standard","hentry","category-mensagens-diversas"],"a3_pvc":{"activated":true,"total_views":890,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=17759"}],"version-history":[{"count":0,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17759\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=17759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=17759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.centronocaminhodaluz.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=17759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}